{"id":3470,"date":"2014-05-05T15:49:14","date_gmt":"2014-05-05T17:49:14","guid":{"rendered":"http:\/\/www.iapop.com\/?p=3470"},"modified":"2025-05-17T10:33:58","modified_gmt":"2025-05-17T09:33:58","slug":"interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork","status":"publish","type":"post","link":"http:\/\/iapop.com\/de\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","title":{"rendered":"Interview mit Arny &amp; Amy Mindell \u00fcber den Zustand der Welt und Worldwork"},"content":{"rendered":"<p><strong>State of the World und Worldwork:<\/strong><\/p>\n<p>Interview mit Amy und Arny Mindell von Bill Say<\/p>\n<p>&nbsp;<\/p>\n<p>1) Was ist Worldwork?<\/p>\n<p>&nbsp;<\/p>\n<p>####<\/p>\n<p>Vielen Dank f\u00fcr das Interview, Bill. Wir sitzen gerade auf dem Flughafen und kommen von einer Reise zur\u00fcck.<\/p>\n<p>worldwork und wir haben Ihre Teamarbeit und die unserer gesamten Belegschaft sehr gesch\u00e4tzt.<\/p>\n<p>&nbsp;<\/p>\n<p>Weltarbeit? Um es kurz zu machen: Es ist eine Art, an Weltfragen zu arbeiten, die sowohl innerlich, beziehungsorientiert, organisatorisch als auch in gro\u00dfen Gruppen funktioniert. Wie die meisten wissen, ist die Demokratie, die auf der Macht des B\u00fcrgers basiert, auf Griechisch \"demo-kratie\", eindeutig ein Schritt weiter im Bewusstsein als die Diktatur.<\/p>\n<p>&nbsp;<\/p>\n<p>Aber auch wenn die Demokratie ein Schritt ist, funktioniert sie nicht immer gut im Sinne einer Verringerung gewaltsamer Konflikte. Der Grund daf\u00fcr ist, dass sie lehrt, wie man Macht teilt, aber nicht, wie man Beziehungen pflegt, die \u00fcber Macht hinausgehen. Der n\u00e4chste Schritt, der \u00fcber die Macht hinausgeht, ist die Entwicklung eines nachhaltigeren Kontakts mit anderen und der F\u00e4higkeit, miteinander zu arbeiten.<\/p>\n<p>&nbsp;<\/p>\n<p>So basiert die Weltarbeit auf dem, was Arny \"tiefe Demokratie\" nannte, die das Bewusstsein und nicht nur die Macht betont. Bewusstsein f\u00fcr Interaktion bedeutet flie\u00dfendere Beziehungen, Bewusstsein f\u00fcr Stimme und K\u00f6rpersignale, Bewusstsein f\u00fcr geteilte momentane und historische Rollen usw. Die \u00e4u\u00dfersten und dramatischsten Aspekte der Weltarbeit zeigen sich in der Arbeit in gro\u00dfen Gruppen, wie wir es gerade in Warschau erlebt haben... erstaunlich... 500 Menschen aus 43 L\u00e4ndern zusammenarbeiten zu sehen.<\/p>\n<p>&nbsp;<\/p>\n<p>2) Was besch\u00e4ftigt Sie heute in Bezug auf Worldwork und die aktuelle Weltlage?<\/p>\n<p>&nbsp;<\/p>\n<p>Wir sind uns der Notwendigkeit bewusst, uns auf L\u00f6sungen und den Wandel der sozialen Systeme zu konzentrieren. Aber nachhaltige Beziehungen sind genauso wichtig oder vielleicht noch wichtiger. Um solche Beziehungen zu erreichen, m\u00fcssen einige von uns lernen, zu moderieren und \u00c4lteste zu sein, die die verschiedenen Seiten und die verschiedenen Rollen innerhalb und au\u00dferhalb von Gruppenprozessen kennen und sich daran beteiligen. Solche \u00c4ltesten k\u00f6nnen Konflikte in flie\u00dfende und kreative Beziehungen verwandeln, in denen die Menschen einander verstehen und zusammenarbeiten.<\/p>\n<p>&nbsp;<\/p>\n<p>3) In vielerlei Hinsicht ist der Zustand der Welt durch die Nachrichten bekannt, die wir durch Zeitungen, Internet, Fernsehen und Radio erhalten. Gibt es irgendetwas \u00fcber den Zustand der Welt, das durch diese allgemeineren Kommunikationsmittel nicht so offensichtlich ist, insbesondere wenn man es aus der Sicht von Worldwork betrachtet?<\/p>\n<p>&nbsp;<\/p>\n<p>Die Nachrichten sind voll von Polarit\u00e4ten, die durch unsere gegenw\u00e4rtige Konsensrealit\u00e4t definiert sind, die von der Kultur, dem Volk und dem Land abh\u00e4ngt. So k\u00f6nnen die \u00e4u\u00dferen Gegner ein Land gegen ein anderes oder ein Volk gegen ein anderes sein.<\/p>\n<p>&nbsp;<\/p>\n<p>Was nicht so offensichtlich ist, ist, dass es immer ein paar Leute gibt, die sich in alle Seiten hineinf\u00fchlen k\u00f6nnen. Und was auch nicht so offensichtlich ist, ist, dass die heutigen Konflikte zum Teil auf nicht verarbeiteten, nicht diskutierten historischen Themen beruhen, die man lieber vergisst, als sie zu verarbeiten. Das ist verst\u00e4ndlich, jeder will Schmerz vermeiden, aber wir brauchen mehr als dieses Vermeiden. Denken wir an die Beziehungen zwischen Russland, Polen, der Ukraine, Deutschland, Italien, Ungarn, Estland, ....... und so weiter. Gerade jetzt in Warschau wurden die Zahlen der 2<sup>und<\/sup> Weltkrieg und die kommunistische \u00c4ra mussten erst erlebt und verarbeitet werden, bevor es zu einer Verst\u00e4ndigung zwischen den Menschen kommen konnte.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>4) Die Lekt\u00fcre \u00fcber den Zustand der Welt kann sehr beunruhigend sein. K\u00f6nnen Sie etwas sagen, das den Zustand der Welt mit dem Prozess der Welt kontrastiert? Und ist der Prozess der Welt Ihrer Meinung nach ebenso alarmierend?<\/p>\n<p>&nbsp;<\/p>\n<p>#### Der Zustand der Welt ist ein \"Zustand\", d.h. ein eingefrorenes Bild, das sich auf das st\u00fctzt, was eine Gruppe sozusagen als die \"Guten\" oder \"B\u00f6sen\" betrachtet.  Wenn wir jedoch beginnen, die Dinge innerhalb von Organisationen oder Gruppen zu verarbeiten, erkennen die Menschen pl\u00f6tzlich, dass sie oft nicht nur eingefroren sind, sondern sich im Stillen ein wenig wie die andere Seite f\u00fchlen. Wenn jemand dies erkennt, kann er oder sie manchmal die Rollen wechseln und fl\u00fcssiger werden und dazu beitragen, eine bewusstere Gemeinschaft zu schaffen. Wenn dies geschieht, erm\u00f6glicht diese Fluidit\u00e4t L\u00f6sungen und Beziehungen, die \u00fcber eine einzige L\u00f6sung hinausgehen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>5) Ihre Arbeit deutet darauf hin, dass Entit\u00e4ten thematische Wurzeln oder Mythen haben, die am Anfang der Dinge stehen, Wurzeln, die oft auf sinnvolle Weise fortbestehen. Haben Sie irgendwelche Gedanken zum grundlegendsten Thema der Welt und von Worldwork?<\/p>\n<p>&nbsp;<\/p>\n<p>###Es gibt viele mythische Wurzeln in einer bestimmten Kultur und einem bestimmten Volk. Einer der wichtigsten Weltmythen zeigt einen Gott, der den ersten Menschen sagt, dass sie im \"Himmel\" bestimmte Dinge nicht tun sollen. Als dies geschieht, wird dieser \"Gott\" zornig und schickt die erste Frau und den ersten Mann auf die Erde, wo der Tod eintreten wird. Diese Geschichte ist wichtig, denn wie dieser \"Gott\" m\u00fcssen wir Stellung beziehen und wie dieser \"Gott\" \"Nein\" zu Dingen sagen, die wir f\u00fcr falsch halten. Aber gleichzeitig ist es keine L\u00f6sung, die Lebensspanne der \"B\u00f6sen\" zu begrenzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir brauchen einen neuen Mythos f\u00fcr nachhaltige L\u00f6sungen, bei denen wir nicht nur streiten und uns \u00fcber andere \u00e4rgern, sondern auch lernen, die Beziehungen zu verarbeiten und mit Menschen auszukommen.<\/p>\n<p>&nbsp;<\/p>\n<p>6) Nach meinem Verst\u00e4ndnis und meiner Erfahrung mit Worldwork scheint es, dass Worldwork eine ungew\u00f6hnliche Art und Weise hat, sich erfahrungsgem\u00e4\u00df auf ein Thema einzulassen, um es zu verstehen, zu entfalten und eine Gemeinschaft aufzubauen. K\u00f6nnen Sie dazu etwas sagen?<\/p>\n<p>&nbsp;<\/p>\n<p>###Ungew\u00f6hnlich? Ja, dieser Begriff h\u00e4ngt nat\u00fcrlich von der Gruppe, der Kultur und der Situation ab.  Manche Gruppen arbeiten daran, die Rollen in sich zu finden. Andere f\u00fchlen sich wohler, wenn sie ihre Rollen ausspielen und in gro\u00dfen Gruppen die Rollen wechseln.<\/p>\n<p>&nbsp;<\/p>\n<p>Wir brauchen eine Welt, vielleicht beginnend mit dem Kindergarten, in der Konflikte offen und sicher in der Gruppe und in der Mitte der Gruppe diskutiert und bearbeitet werden k\u00f6nnen. In gewisser Weise brauchen wir neue Kinderg\u00e4rten, und so k\u00f6nnen neue Welten entstehen.<\/p>\n<p>&nbsp;<\/p>\n<p>7) K\u00f6nnen Sie unseren sehr unterschiedlichen Zuschauern, die vielleicht ein unterschiedliches Ma\u00df an Eingliederung oder Ausgrenzung, an Macht oder deren Fehlen erleben und dennoch nach besseren M\u00f6glichkeiten des Zusammenlebens und -arbeitens suchen, irgendwelche allgemeinen Vorschl\u00e4ge machen?<\/p>\n<p>&nbsp;<\/p>\n<p>Ja, folgen Sie Ihrem eigenen Ich, Ihren eigenen Tr\u00e4umen. Sprechen Sie, wenn m\u00f6glich, \u00fcber Konflikte mit anderen und zeigen Sie auf, wie Sie selbst Konflikte verursachen k\u00f6nnen, indem Sie rangunbewusst sind. Jeder von uns hat einen gewissen Rang und eine gewisse Macht. Stehen Sie dazu, und seien Sie sich dann bewusst, dass dies \"Machtk\u00e4mpfe\" mit anderen irritieren und entfachen kann. Mit anderen Worten: Nehmen Sie Stellung, verstehen Sie den anderen und seien Sie er selbst.<\/p>\n<p>&nbsp;<\/p>\n<p>8) Es scheint, dass viele Menschen und Gruppen die Welt ver\u00e4ndern, beeinflussen oder anderweitig mit ihr zusammenarbeiten m\u00f6chten und sich dennoch unsicher f\u00fchlen, wie sie ihre Wirkung maximieren k\u00f6nnen. K\u00f6nnen Sie denjenigen, die damit zu k\u00e4mpfen haben, wie sie die Welt am besten ver\u00e4ndern k\u00f6nnen, irgendwelche Ideen oder Ermutigungen anbieten?<\/p>\n<p>&nbsp;<\/p>\n<p>####Yes, genie\u00dfe jeden Komfort, den du finden kannst, und gehe dann in Gruppen und Kulturen, \u00fcber die du nicht viel wei\u00dft oder in denen du dich unwohl f\u00fchlst, um etwas \u00fcber andere Kommunikationsstile und Lebensweisen zu lernen. Schaffen Sie mehr Gemeinschaft unter allen V\u00f6lkern, tun Sie es auf Ihre eigene Art, aber tun Sie es.<\/p>\n<p>&nbsp;<\/p>\n<p>9) Ich wei\u00df, dass Sie bei Ihrer Arbeit mit Gruppen in der ganzen Welt viel gelernt haben. Gibt es irgendwelche besonderen Lektionen, die Ihnen heute in den Sinn kommen?<\/p>\n<p>&nbsp;<\/p>\n<p>Jeder, auch die B\u00f6sewichte, sind Teil unserer Familie. Au\u00dferdem gibt es grundlegende Prozessstrukturen, die alle Gruppen unabh\u00e4ngig von ihrer Kultur erleben. In allen Gruppen wird getratscht, es gibt Geisterrollen und doppelte Signale. Und in fast jeder Gruppe gibt es \u00c4lteste, die aus dem \"Nichts\" auftauchen... die oft nicht die designierten Moderatoren sind. Diese Menschen halten ihre Arme offen und sind f\u00fcr alle da und k\u00f6nnen sich ins Feuer setzen.<\/p>\n<p>&nbsp;<\/p>\n<p>10) Viele Gruppen, Organisationen und Gemeinschaften haben mit Konflikten zu k\u00e4mpfen. Haben Sie irgendwelche Vorschl\u00e4ge?<\/p>\n<p>&nbsp;<\/p>\n<p>###K\u00e4mpfen Sie, sch\u00fctzen Sie sich, dann denken Sie, wie sind wir die anderen.<\/p>\n<p>&nbsp;<\/p>\n<p>11) Wie entwickelt sich Worldwork und spiegelt seine Entwicklung eine gr\u00f6\u00dfere globale Tendenz wider?<\/p>\n<p>&nbsp;<\/p>\n<p>####Das Interesse an der Weltarbeit ist weltweit gr\u00f6\u00dfer denn je - und viele F\u00fchrungskr\u00e4fte sind interessiert, scheuen sich aber, dies \u00f6ffentlich zu sagen. Aber der Wandel wird f\u00fcr uns eintreten, wenn wir schon im Kindergarten damit beginnen und Kinder auf dem Spielplatz Weltarbeit praktizieren lassen.<\/p>\n<p>&nbsp;<\/p>\n<p>12) Amy, in einem Vortrag, den Sie und Arny letztes Jahr in Yachats \u00fcber Worldwork gehalten haben, sprachen Sie davon, dass Sie hoffnungsvoll sind \u00fcber das, was Sie in Ihrer Arbeit mit verschiedenen Gruppen in der ganzen Welt sehen. K\u00f6nnen Sie etwas zu dieser Hoffnung sagen?<\/p>\n<p>&nbsp;<\/p>\n<p>#### ja, wenn eine Gruppe sich bewusst macht, wo die Menschen stehen, und verschiedene Instrumente einsetzt, k\u00f6nnen erstaunliche Dinge geschehen. Menschen k\u00f6nnen konfliktreich sein, aber mit etwas Bewusstsein k\u00f6nnen Gruppen erstaunlich sein. Wir haben das in Verbindungen mit Organisationen, Interessengruppen, Kirchen, UN-Gruppen und Menschen auf der ganzen Welt erlebt.<\/p>\n<p>&nbsp;<\/p>\n<p>13) Michal Wertheimer Shimoni stellte eine Frage nach Ratschl\u00e4gen f\u00fcr Menschen, die in Konfliktgebieten leben.<\/p>\n<p>&nbsp;<\/p>\n<p>###YES: K\u00fcmmern Sie sich zuerst um sich selbst, und beginnen Sie dann, vorsichtig und konservativ den Gegner und die fl\u00fcssigen Interaktionen auszuspielen, indem Sie in Rollenspielen demonstrieren, wie Sie das mit Ihren Freunden und Gruppen machen. Der Schl\u00fcssel liegt darin, manchmal der Gegner zu sein, der gegen sich selbst argumentiert.<\/p>\n<p>&nbsp;<\/p>\n<p>14) Matt Stella stellte eine Frage zur Anwendung von Worldwork in einem Gebiet, in dem die Bev\u00f6lkerung ziemlich homogen ist.<\/p>\n<p>&nbsp;<\/p>\n<p>###Wunderbar. Bauen Sie ihren Stolz auf und f\u00fchren Sie dann langsam die Rollen der anderen Gruppen ein, die vielleicht nicht anwesend sind. Und wie? Zeigen Sie dies beim Einkaufen, am Flughafen und auf den Stra\u00dfen der Stadt \uf04a<\/p>","protected":false},"excerpt":{"rendered":"<p>State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]<\/p>\n","protected":false},"author":181,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-3470","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview with Arny &amp; Amy Mindell on State of the World and Worldwork - IAPOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iapop.com\/de\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview with Arny &amp; Amy Mindell on State of the World and Worldwork - IAPOP\" \/>\n<meta property=\"og:description\" content=\"State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iapop.com\/de\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/\" \/>\n<meta property=\"og:site_name\" content=\"IAPOP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/processwork.iapop\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-05T17:49:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T09:33:58+00:00\" \/>\n<meta name=\"author\" content=\"Bill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"},\"author\":{\"name\":\"Bill\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/person\\\/371712f2393f00a3f6c06d182a184fba\"},\"headline\":\"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork\",\"datePublished\":\"2014-05-05T17:49:14+00:00\",\"dateModified\":\"2025-05-17T09:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"},\"wordCount\":1544,\"publisher\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\",\"url\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\",\"name\":\"Interview with Arny & Amy Mindell on State of the World and Worldwork - IAPOP\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#website\"},\"datePublished\":\"2014-05-05T17:49:14+00:00\",\"dateModified\":\"2025-05-17T09:33:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iapop.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/iapop.com\\\/es\\\/\",\"name\":\"IAPOP\",\"description\":\"Process Oriented Psychology\",\"publisher\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/iapop.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\",\"name\":\"IAPOP\",\"url\":\"http:\\\/\\\/iapop.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iapop.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-300x131-1.png\",\"contentUrl\":\"https:\\\/\\\/iapop.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-300x131-1.png\",\"width\":300,\"height\":131,\"caption\":\"IAPOP\"},\"image\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/processwork.iapop\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/person\\\/371712f2393f00a3f6c06d182a184fba\",\"name\":\"Bill\",\"url\":\"http:\\\/\\\/iapop.com\\\/de\\\/author\\\/bill\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview mit Arny &amp; Amy Mindell \u00fcber den Zustand der Welt und Worldwork - IAPOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iapop.com\/de\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","og_locale":"de_DE","og_type":"article","og_title":"Interview with Arny & Amy Mindell on State of the World and Worldwork - IAPOP","og_description":"State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]","og_url":"https:\/\/iapop.com\/de\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","og_site_name":"IAPOP","article_publisher":"https:\/\/www.facebook.com\/processwork.iapop","article_published_time":"2014-05-05T17:49:14+00:00","article_modified_time":"2025-05-17T09:33:58+00:00","author":"Bill","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Bill","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#article","isPartOf":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"},"author":{"name":"Bill","@id":"http:\/\/iapop.com\/es\/#\/schema\/person\/371712f2393f00a3f6c06d182a184fba"},"headline":"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork","datePublished":"2014-05-05T17:49:14+00:00","dateModified":"2025-05-17T09:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"},"wordCount":1544,"publisher":{"@id":"http:\/\/iapop.com\/es\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","url":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","name":"Interview mit Arny &amp; Amy Mindell \u00fcber den Zustand der Welt und Worldwork - IAPOP","isPartOf":{"@id":"http:\/\/iapop.com\/es\/#website"},"datePublished":"2014-05-05T17:49:14+00:00","dateModified":"2025-05-17T09:33:58+00:00","breadcrumb":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iapop.com\/"},{"@type":"ListItem","position":2,"name":"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork"}]},{"@type":"WebSite","@id":"http:\/\/iapop.com\/es\/#website","url":"http:\/\/iapop.com\/es\/","name":"IAPOP","description":"Prozessorientierte Psychologie","publisher":{"@id":"http:\/\/iapop.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/iapop.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"http:\/\/iapop.com\/es\/#organization","name":"IAPOP","url":"http:\/\/iapop.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/iapop.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/iapop.com\/wp-content\/uploads\/2024\/12\/Logo-300x131-1.png","contentUrl":"https:\/\/iapop.com\/wp-content\/uploads\/2024\/12\/Logo-300x131-1.png","width":300,"height":131,"caption":"IAPOP"},"image":{"@id":"http:\/\/iapop.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/processwork.iapop"]},{"@type":"Person","@id":"http:\/\/iapop.com\/es\/#\/schema\/person\/371712f2393f00a3f6c06d182a184fba","name":"Rechnung","url":"http:\/\/iapop.com\/de\/author\/bill\/"}]}},"_links":{"self":[{"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/posts\/3470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/comments?post=3470"}],"version-history":[{"count":2,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/posts\/3470\/revisions"}],"predecessor-version":[{"id":7524,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/posts\/3470\/revisions\/7524"}],"wp:attachment":[{"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/media?parent=3470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/categories?post=3470"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iapop.com\/de\/wp-json\/wp\/v2\/tags?post=3470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}