{"id":3470,"date":"2014-05-05T15:49:14","date_gmt":"2014-05-05T17:49:14","guid":{"rendered":"http:\/\/www.iapop.com\/?p=3470"},"modified":"2025-05-17T10:33:58","modified_gmt":"2025-05-17T09:33:58","slug":"interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork","status":"publish","type":"post","link":"http:\/\/iapop.com\/fr\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","title":{"rendered":"Entretien avec Arny et Amy Mindell sur l'\u00e9tat du monde et le travail mondial"},"content":{"rendered":"<p><strong>L'\u00e9tat du monde et Worldwork :<\/strong><\/p>\n<p>Entretien avec Amy et Arny Mindell par Bill Say<\/p>\n<p>&nbsp;<\/p>\n<p>1) Qu'est-ce que Worldwork ?<\/p>\n<p>&nbsp;<\/p>\n<p>####<\/p>\n<p>Merci de nous avoir interview\u00e9s, Bill. Nous sommes en ce moment m\u00eame \u00e0 l'a\u00e9roport, en train de revenir de<\/p>\n<p>Nous avons appr\u00e9ci\u00e9 votre travail d'\u00e9quipe et celui de l'ensemble de notre personnel.<\/p>\n<p>&nbsp;<\/p>\n<p>Le travail mondial ? En bref, il s'agit d'une mani\u00e8re de travailler sur les questions mondiales qui est \u00e0 la fois int\u00e9rieure, orient\u00e9e vers les relations, organisationnelle et en grand groupe. Comme la plupart des gens le savent, la d\u00e9mocratie, qui est bas\u00e9e sur le pouvoir des citoyens, c'est-\u00e0-dire la \"d\u00e9mo-kratie\" en grec, est clairement un pas en avant dans la conscience par rapport \u00e0 la dictature.<\/p>\n<p>&nbsp;<\/p>\n<p>Mais m\u00eame si la d\u00e9mocratie est une \u00e9tape, elle ne permet pas toujours de r\u00e9duire les conflits violents. Pourquoi ? parce qu'elle enseigne le partage du pouvoir, mais pas les relations, qui vont au-del\u00e0 du pouvoir. L'\u00e9tape suivante, au-del\u00e0 du pouvoir, consiste \u00e0 d\u00e9velopper des contacts plus durables avec les autres et la capacit\u00e9 de travailler les uns avec les autres.<\/p>\n<p>&nbsp;<\/p>\n<p>Ainsi, le travail mondial est bas\u00e9 sur ce qu'Arny a appel\u00e9 la \"d\u00e9mocratie profonde\", qui met l'accent sur la conscience, et pas seulement sur le pouvoir. La conscience de l'interaction signifie des relations plus fluides, la conscience des signaux vocaux et corporels, la conscience des r\u00f4les momentan\u00e9s et historiques partag\u00e9s, etc. Les aspects les plus ext\u00e9rieurs et les plus spectaculaires du travail mondial apparaissent dans les grands groupes, comme nous venons de l'exp\u00e9rimenter \u00e0 Varsovie... incroyable... de voir 500 personnes de 43 pays travailler ensemble...<\/p>\n<p>&nbsp;<\/p>\n<p>2) Qu'est-ce qui vous pr\u00e9occupe aujourd'hui en ce qui concerne le travail mondial et la situation mondiale actuelle ?<\/p>\n<p>&nbsp;<\/p>\n<p>Nous sommes tr\u00e8s conscients de la n\u00e9cessit\u00e9 de nous concentrer sur les solutions et le changement des syst\u00e8mes sociaux. Mais les relations durables sont tout aussi importantes, voire plus. Pour parvenir \u00e0 de telles relations, certains d'entre nous doivent apprendre \u00e0 faciliter les choses et \u00e0 \u00eatre des a\u00een\u00e9s qui connaissent et participent aux diff\u00e9rentes parties et aux diff\u00e9rents r\u00f4les \u00e0 l'int\u00e9rieur d'eux-m\u00eames et \u00e0 l'ext\u00e9rieur dans les processus de groupe. Ces a\u00een\u00e9s peuvent transformer les conflits en relations fluides et cr\u00e9atives o\u00f9 les gens se comprennent et travaillent ensemble.<\/p>\n<p>&nbsp;<\/p>\n<p>3) A bien des \u00e9gards, l'\u00e9tat du monde est connu \u00e0 travers les nouvelles que nous recevons par le biais des journaux, d'Internet, de la t\u00e9l\u00e9vision et de la radio. Y a-t-il un aspect de l'\u00e9tat du monde qui n'est pas aussi \u00e9vident par le biais de ces moyens de communication les plus courants, en particulier si on l'examine du point de vue du travail mondial ?<\/p>\n<p>&nbsp;<\/p>\n<p>L'actualit\u00e9 est pleine de polarit\u00e9s d\u00e9finies par notre r\u00e9alit\u00e9 consensuelle actuelle, qui d\u00e9pend de la culture, du peuple et du pays. Ainsi, les opposants ext\u00e9rieurs peuvent \u00eatre un pays contre un autre, ou un peuple contre un autre.<\/p>\n<p>&nbsp;<\/p>\n<p>Ce qui n'est pas si \u00e9vident, c'est qu'il y a toujours quelques personnes capables de comprendre toutes les parties. Ce qui n'est pas \u00e9vident non plus, c'est que les conflits actuels reposent dans une certaine mesure sur des questions historiques non r\u00e9solues et non discut\u00e9es que les gens pr\u00e9f\u00e8rent oublier au lieu de les traiter. C'est compr\u00e9hensible, tout le monde veut \u00e9viter la douleur, mais nous avons besoin de plus que cet \u00e9vitement. Pensons aux relations entre la Russie, la Pologne, l'Ukraine, l'Allemagne, l'Italie, la Hongrie, l'Estonie, ....... Etc. En ce moment m\u00eame, \u00e0 Varsovie, les chiffres des 2<sup>nd<\/sup> La guerre mondiale et l'\u00e8re communiste devaient d'abord \u00eatre v\u00e9cues et trait\u00e9es avant qu'une quelconque compr\u00e9hension ne puisse s'\u00e9tablir entre les personnes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>4) La lecture de l'\u00e9tat du monde peut \u00eatre tr\u00e8s alarmante. Pouvez-vous dire quelque chose qui contraste l'\u00e9tat du monde avec le processus du monde ? Et le processus du monde est-il aussi alarmant \u00e0 vos yeux ?<\/p>\n<p>&nbsp;<\/p>\n<p>#### L'\u00e9tat du monde est un \"\u00e9tat\", c'est-\u00e0-dire une image fig\u00e9e qui est cens\u00e9e \u00eatre bas\u00e9e sur ce qu'un groupe consid\u00e8re comme les \"bons\" ou les \"m\u00e9chants\", pour ainsi dire.  Cependant, lorsque nous commen\u00e7ons \u00e0 traiter les choses \u00e0 l'int\u00e9rieur d'une organisation ou d'un groupe, les gens r\u00e9alisent soudain qu'ils ne sont pas seulement fig\u00e9s, mais qu'ils se sentent en quelque sorte de l'autre c\u00f4t\u00e9. Lorsque quelqu'un s'en rend compte, il ou elle peut parfois changer de r\u00f4le, devenir plus fluide et contribuer \u00e0 cr\u00e9er une communaut\u00e9 plus consciente. Lorsque cela se produit, cette fluidit\u00e9 permet de trouver des solutions et d'\u00e9tablir des relations au-del\u00e0 de toute solution unique.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>5) Votre travail sugg\u00e8re que les entit\u00e9s ont des racines th\u00e9matiques, ou des mythes, qui sont pr\u00e9sents au tout d\u00e9but des choses, des racines qui perdurent souvent de mani\u00e8re significative. Avez-vous des id\u00e9es sur le th\u00e8me le plus fondamental du monde et du Worldwork ?<\/p>\n<p>&nbsp;<\/p>\n<p>###les racines mythiques d'une culture et d'un peuple donn\u00e9 sont nombreuses. L'un des principaux mythes mondiaux montre un Dieu qui dit aux premiers hommes de ne pas faire certaines choses au \"ciel\". Lorsque cela se produit, ce \"Dieu\" se met en col\u00e8re et envoie la premi\u00e8re femme et le premier homme sur terre, o\u00f9 la mort survient. Cette histoire est importante car, comme ce \"Dieu\", nous devons prendre position et, comme lui, dire \"non\" aux choses que nous jugeons mauvaises. Mais en m\u00eame temps, limiter la dur\u00e9e de vie des \"m\u00e9chants\" n'est pas une solution.<\/p>\n<p>&nbsp;<\/p>\n<p>Nous avons besoin d'un nouveau mythe pour des r\u00e9solutions durables dans lesquelles nous ne nous contentons pas d'\u00eatre en d\u00e9saccord et de nous f\u00e2cher avec les autres, mais o\u00f9 nous apprenons aussi \u00e0 g\u00e9rer les relations et \u00e0 nous entendre avec les gens.<\/p>\n<p>&nbsp;<\/p>\n<p>6) D'apr\u00e8s ma compr\u00e9hension et mon exp\u00e9rience du Worldwork, il semble que ce dernier ait une fa\u00e7on inhabituelle d'entrer de mani\u00e8re exp\u00e9rimentale dans une question afin de la comprendre, de la d\u00e9plier et de construire une communaut\u00e9. Pouvez-vous nous en dire plus \u00e0 ce sujet ?<\/p>\n<p>&nbsp;<\/p>\n<p>###Unusual ? Oui, ce terme d\u00e9pend bien s\u00fbr du groupe, de la culture et de la situation.  Certains groupes s'efforceront de trouver les r\u00f4les \u00e0 l'int\u00e9rieur. D'autres sont plus \u00e0 l'aise en jouant les r\u00f4les et en changeant de r\u00f4le dans les grands groupes.<\/p>\n<p>&nbsp;<\/p>\n<p>Nous avons besoin d'un monde, peut-\u00eatre en commen\u00e7ant par le jardin d'enfants, o\u00f9 les conflits peuvent \u00eatre discut\u00e9s et trait\u00e9s ouvertement et en toute s\u00e9curit\u00e9 \u00e0 l'int\u00e9rieur et au milieu du groupe. D'une certaine mani\u00e8re, nous avons besoin de nouveaux jardins d'enfants, ce qui permettra \u00e0 de nouveaux mondes de voir le jour.<\/p>\n<p>&nbsp;<\/p>\n<p>7) Pour nos t\u00e9l\u00e9spectateurs tr\u00e8s diff\u00e9rents qui peuvent conna\u00eetre divers degr\u00e9s d'inclusion ou d'exclusion, de pouvoir ou d'absence de pouvoir, et qui cherchent pourtant de meilleures fa\u00e7ons de vivre et de travailler ensemble, pouvez-vous formuler des suggestions g\u00e9n\u00e9rales ?<\/p>\n<p>&nbsp;<\/p>\n<p>Oui, suivez votre propre chemin, vos propres r\u00eaves. Si possible, parlez des conflits avec les autres et montrez comment vous pouvez vous-m\u00eame cr\u00e9er des conflits en \u00e9tant inconscient de votre rang. Chacun d'entre nous a un certain rang et un certain pouvoir, d\u00e9fendez-le, puis soyez conscient que cela peut irriter et attiser les \"luttes de pouvoir\" avec les autres. En d'autres termes, prenez position, puis comprenez l'autre et soyez-le.<\/p>\n<p>&nbsp;<\/p>\n<p>8) Il semble que de nombreuses personnes et de nombreux groupes souhaitent changer le monde, avoir un impact sur lui ou travailler avec lui d'une autre mani\u00e8re, mais ne savent pas toujours comment maximiser leur impact. Pouvez-vous proposer des id\u00e9es ou des encouragements \u00e0 ceux qui se d\u00e9battent avec la question de savoir comment faire la diff\u00e9rence dans ce monde ?<\/p>\n<p>&nbsp;<\/p>\n<p>####Yes, profitez de tout le confort que vous pouvez trouver, puis allez dans des groupes et des cultures que vous ne connaissez pas beaucoup, ou dans lesquels vous ne vous sentez pas \u00e0 l'aise, afin d'apprendre les diff\u00e9rents styles de communication et les diff\u00e9rentes fa\u00e7ons d'\u00eatre. Cr\u00e9ez plus de communaut\u00e9 entre tous les peuples, faites-le \u00e0 votre mani\u00e8re, mais faites-le.<\/p>\n<p>&nbsp;<\/p>\n<p>9) Je sais que vous avez appris beaucoup de choses en travaillant avec des groupes du monde entier, y a-t-il des le\u00e7ons particuli\u00e8res qui vous viennent \u00e0 l'esprit aujourd'hui ?<\/p>\n<p>&nbsp;<\/p>\n<p>Tout le monde, m\u00eame les m\u00e9chants, fait partie de notre famille. Par ailleurs, il existe des structures de processus de base que tous les groupes connaissent, quelle que soit leur culture. Tous les groupes font des comm\u00e9rages, ont des r\u00f4les fant\u00f4mes, des doubles signaux. Et dans presque tous les groupes, il y a des anciens qui sortent de \"nulle part\"... qui ne sont souvent pas les facilitateurs d\u00e9sign\u00e9s. Ces personnes ouvrent les bras, sont l\u00e0 pour tout le monde et peuvent s'asseoir dans le feu.<\/p>\n<p>&nbsp;<\/p>\n<p>10) De nombreux groupes, organisations et communaut\u00e9s sont confront\u00e9s \u00e0 des conflits. Avez-vous des suggestions \u00e0 faire ?<\/p>\n<p>&nbsp;<\/p>\n<p>##1TP5Combattre, se prot\u00e9ger, puis r\u00e9fl\u00e9chir \u00e0 la fa\u00e7on dont l'autre se comporte.<\/p>\n<p>&nbsp;<\/p>\n<p>11) Comment \u00e9volue le Worldwork et son \u00e9volution refl\u00e8te-t-elle une tendance globale plus importante ?<\/p>\n<p>&nbsp;<\/p>\n<p>###1TP5Le travail mondial suscite plus d'int\u00e9r\u00eat que jamais dans le monde entier - et de nombreux dirigeants s'y int\u00e9ressent, mais n'osent pas le dire publiquement. Mais le changement se produira pour nous si nous commen\u00e7ons \u00e0 changer d\u00e8s le jardin d'enfants, en demandant aux enfants de pratiquer le travail mondial dans la cour de r\u00e9cr\u00e9ation.<\/p>\n<p>&nbsp;<\/p>\n<p>12) Amy, lors d'une conf\u00e9rence que vous avez donn\u00e9e avec Arny \u00e0 Yachats l'ann\u00e9e derni\u00e8re sur le travail mondial, vous avez parl\u00e9 de l'espoir que vous inspire votre travail avec diff\u00e9rents groupes dans le monde. Pourriez-vous nous parler de cet espoir ?<\/p>\n<p>&nbsp;<\/p>\n<p>#### oui, lorsqu'un groupe est conscient et appr\u00e9cie la situation des gens et utilise divers outils, des choses \u00e9tonnantes se produisent. Les gens peuvent \u00eatre conflictuels, mais avec un peu de conscience, les groupes peuvent \u00eatre extraordinaires. Nous avons vu cela se produire dans le cadre de connexions avec des organisations, des groupes d'int\u00e9r\u00eat, des \u00e9glises, des groupes de l'ONU et des personnes du monde entier.<\/p>\n<p>&nbsp;<\/p>\n<p>13) Michal Wertheimer Shimoni a pos\u00e9 une question sur les conseils \u00e0 donner aux personnes vivant dans des zones de conflit.<\/p>\n<p>&nbsp;<\/p>\n<p>###Yes, prenez d'abord soin de vous, puis commencez \u00e0 jouer avec soin et prudence les interactions entre l'adversaire et les fluides, en d\u00e9montrant par des jeux de r\u00f4le comment proc\u00e9der avec vos amis et vos groupes. La cl\u00e9 est d'\u00eatre parfois l'opposant qui argumente contre soi-m\u00eame.<\/p>\n<p>&nbsp;<\/p>\n<p>14) Matt Stella a pos\u00e9 une question sur l'application de Worldwork dans une r\u00e9gion o\u00f9 la population est assez homog\u00e8ne.<\/p>\n<p>&nbsp;<\/p>\n<p>###Merveilleux. Renforcez leur fiert\u00e9, puis introduisez progressivement les r\u00f4les des autres groupes qui ne sont peut-\u00eatre pas pr\u00e9sents. Comment ? Montrez-le en faisant les courses, \u00e0 l'a\u00e9roport et dans les rues de la ville \uf04a<\/p>","protected":false},"excerpt":{"rendered":"<p>State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]<\/p>\n","protected":false},"author":181,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3470","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview with Arny &amp; Amy Mindell on State of the World and Worldwork - IAPOP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iapop.com\/fr\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview with Arny &amp; Amy Mindell on State of the World and Worldwork - IAPOP\" \/>\n<meta property=\"og:description\" content=\"State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iapop.com\/fr\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/\" \/>\n<meta property=\"og:site_name\" content=\"IAPOP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/processwork.iapop\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-05T17:49:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T09:33:58+00:00\" \/>\n<meta name=\"author\" content=\"Bill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"},\"author\":{\"name\":\"Bill\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/person\\\/371712f2393f00a3f6c06d182a184fba\"},\"headline\":\"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork\",\"datePublished\":\"2014-05-05T17:49:14+00:00\",\"dateModified\":\"2025-05-17T09:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"},\"wordCount\":1542,\"publisher\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\"},\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\",\"url\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\",\"name\":\"Interview with Arny & Amy Mindell on State of the World and Worldwork - IAPOP\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#website\"},\"datePublished\":\"2014-05-05T17:49:14+00:00\",\"dateModified\":\"2025-05-17T09:33:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iapop.com\\\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iapop.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/iapop.com\\\/es\\\/\",\"name\":\"IAPOP\",\"description\":\"Process Oriented Psychology\",\"publisher\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/iapop.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#organization\",\"name\":\"IAPOP\",\"url\":\"http:\\\/\\\/iapop.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iapop.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-300x131-1.png\",\"contentUrl\":\"https:\\\/\\\/iapop.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-300x131-1.png\",\"width\":300,\"height\":131,\"caption\":\"IAPOP\"},\"image\":{\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/processwork.iapop\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/iapop.com\\\/es\\\/#\\\/schema\\\/person\\\/371712f2393f00a3f6c06d182a184fba\",\"name\":\"Bill\",\"url\":\"http:\\\/\\\/iapop.com\\\/fr\\\/author\\\/bill\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entretien avec Arny et Amy Mindell sur l'\u00e9tat du monde et le travail mondial - IAPOP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iapop.com\/fr\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","og_locale":"fr_FR","og_type":"article","og_title":"Interview with Arny & Amy Mindell on State of the World and Worldwork - IAPOP","og_description":"State of the World and Worldwork: Interview with Amy and Arny Mindell by Bill Say &nbsp; 1)What is Worldwork? &nbsp; #### Thanks for interviewing us Bill, we are sitting in [&hellip;]","og_url":"https:\/\/iapop.com\/fr\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","og_site_name":"IAPOP","article_publisher":"https:\/\/www.facebook.com\/processwork.iapop","article_published_time":"2014-05-05T17:49:14+00:00","article_modified_time":"2025-05-17T09:33:58+00:00","author":"Bill","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bill","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#article","isPartOf":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"},"author":{"name":"Bill","@id":"http:\/\/iapop.com\/es\/#\/schema\/person\/371712f2393f00a3f6c06d182a184fba"},"headline":"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork","datePublished":"2014-05-05T17:49:14+00:00","dateModified":"2025-05-17T09:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"},"wordCount":1542,"publisher":{"@id":"http:\/\/iapop.com\/es\/#organization"},"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","url":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/","name":"Entretien avec Arny et Amy Mindell sur l'\u00e9tat du monde et le travail mondial - IAPOP","isPartOf":{"@id":"http:\/\/iapop.com\/es\/#website"},"datePublished":"2014-05-05T17:49:14+00:00","dateModified":"2025-05-17T09:33:58+00:00","breadcrumb":{"@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iapop.com\/interview-with-arny-amy-mindell-on-state-of-the-world-and-worldwork\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iapop.com\/"},{"@type":"ListItem","position":2,"name":"Interview with Arny &#038; Amy Mindell on State of the World and Worldwork"}]},{"@type":"WebSite","@id":"http:\/\/iapop.com\/es\/#website","url":"http:\/\/iapop.com\/es\/","name":"IAPOP","description":"Psychologie ax\u00e9e sur les processus","publisher":{"@id":"http:\/\/iapop.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/iapop.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/iapop.com\/es\/#organization","name":"IAPOP","url":"http:\/\/iapop.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/iapop.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/iapop.com\/wp-content\/uploads\/2024\/12\/Logo-300x131-1.png","contentUrl":"https:\/\/iapop.com\/wp-content\/uploads\/2024\/12\/Logo-300x131-1.png","width":300,"height":131,"caption":"IAPOP"},"image":{"@id":"http:\/\/iapop.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/processwork.iapop"]},{"@type":"Person","@id":"http:\/\/iapop.com\/es\/#\/schema\/person\/371712f2393f00a3f6c06d182a184fba","name":"Projet de loi","url":"http:\/\/iapop.com\/fr\/author\/bill\/"}]}},"_links":{"self":[{"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/posts\/3470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/comments?post=3470"}],"version-history":[{"count":2,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/posts\/3470\/revisions"}],"predecessor-version":[{"id":7524,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/posts\/3470\/revisions\/7524"}],"wp:attachment":[{"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/media?parent=3470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/categories?post=3470"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/iapop.com\/fr\/wp-json\/wp\/v2\/tags?post=3470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}